{"id":99351,"date":"2024-04-29T16:14:01","date_gmt":"2024-04-29T14:14:01","guid":{"rendered":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/"},"modified":"2024-07-30T13:27:09","modified_gmt":"2024-07-30T11:27:09","slug":"lo-quiero-todo-de-ti","status":"publish","type":"product","link":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/","title":{"rendered":"Lo quiero todo de ti"},"content":{"rendered":"<p><strong>ISBN<\/strong>: 978-84-1144-943-4<\/p>\n<p><strong>T\u00edtulo<\/strong>: Lo quiero todo de ti<br \/>\n<strong>Fecha<\/strong>: 2023<br \/>\n<strong>P\u00e1ginas<\/strong>: 212<\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>LO QUIERO TODO DE TI es la bonita historia de amor de JESUS y ANABEL unos amigos, que desde peque\u00f1os hicieron novillos en la plaza de su barrio, entre juego y juego, cada vez se acercaban mas sus corazones, casi sin querer, como por inercia, pero el respeto mutuo entre los dos, encorsetaba de alguna forma el idilio reciproco que por su mismo impulso hubiera florecido. JESUS, en su temor de perderla, le dio un brote de valent\u00eda de los que solo le dan a los que est\u00e1n luchando por su amor, bes\u00f3 a ANABEL en los labios creyendo que as\u00ed ya seria para \u00e9l, pero \u00e9sta se asusto o mas bien sus propios pensamientos le jug\u00f3 una mala pasada y a partir de ah\u00ed, su vida no tiene nada que ver con la vida que so\u00f1aba, ni con quien la so\u00f1aba, y aunque tuvo la posibilidad de tener lo que quisiera en la vida, su esencia de mujer se lo repel\u00eda, se dio cuenta tarde de que escogi\u00f3 una vida que no comulgaba con ella, y por consecuencia, la vida le zarandeo, aunque ella supo salir ilesa en conciencia. Y ademas pudo comprobar con todos sus sentidos, que lo que el amor te quita, te lo devuelve con intereses y te hace querer, y queriendo todo de la otra persona. El amor al igual que cuando no muere puede matar, cuando revive te sana desde un ara\u00f1azo hasta el dolor del coraz\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>ISBN<\/strong>: 978-84-1144-943-4<\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>LO QUIERO TODO DE TI es la bonita historia de amor de JESUS y ANABEL unos amigos, que desde peque\u00f1os hicieron novillos en la plaza de su barrio, entre juego y juego, cada vez se acercaban mas sus corazones, casi sin querer, como por inercia, pero el respeto mutuo entre los dos, encorsetaba de alguna forma el idilio reciproco que por su mismo impulso hubiera florecido. JESUS, en su temor de perderla, le dio un brote de valent\u00eda de los que solo le dan a los que est\u00e1n luchando por su amor, bes\u00f3 a ANABEL en los labios creyendo que as\u00ed ya seria para \u00e9l, pero \u00e9sta se asusto o mas bien sus propios pensamientos le jug\u00f3 una mala pasada y a partir de ah\u00ed, su vida no tiene nada que ver con la vida que so\u00f1aba, ni con quien la so\u00f1aba, y aunque tuvo la posibilidad de tener lo que quisiera en la vida, su esencia de mujer se lo repel\u00eda, se dio cuenta tarde de que escogi\u00f3 una vida que no comulgaba con ella, y por consecuencia, la vida le zarandeo, aunque ella supo salir ilesa en conciencia. Y ademas pudo comprobar con todos sus sentidos, que lo que el amor te quita, te lo devuelve con intereses y te hace querer, y queriendo todo de la otra persona. El amor al igual que cuando no muere puede matar, cuando revive te sana desde un ara\u00f1azo hasta el dolor del coraz\u00f3n.<\/p>\n","protected":false},"featured_media":99352,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"libro":[],"product_brand":[],"product_cat":[26],"product_tag":[],"class_list":["post-99351","product","type-product","status-publish","has-post-thumbnail","product_cat-sin-categoria","first","instock","product-type-simple"],"acf":{"autor":[77702],"enlace_de_compra":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"ISBN: 978-84-1144-943-4  SINOPSIS  LO QUIERO TODO DE TI es la bonita historia de amor de JESUS y ANABEL unos amigos, que desde peque\u00f1os hicieron novillos en la plaza de su barrio, entre juego y juego, cada vez se acercaban mas sus corazones, casi sin querer, como por inercia, pero el respeto mutuo entre los dos, encorsetaba de alguna forma el idilio reciproco que por su mismo impulso hubiera florecido. JESUS, en su temor de perderla, le dio un brote de valent\u00eda de los que solo le dan a los que est\u00e1n luchando por su amor, bes\u00f3 a ANABEL en los labios creyendo que as\u00ed ya seria para \u00e9l, pero \u00e9sta se asusto o mas bien sus propios pensamientos le jug\u00f3 una mala pasada y a partir de ah\u00ed, su vida no tiene nada que ver con la vida que so\u00f1aba, ni con quien la so\u00f1aba, y aunque tuvo la posibilidad de tener lo que quisiera en la vida, su esencia de mujer se lo repel\u00eda, se dio cuenta tarde de que escogi\u00f3 una vida que no comulgaba con ella, y por consecuencia, la vida le zarandeo, aunque ella supo salir ilesa en conciencia. Y ademas pudo comprobar con todos sus sentidos, que lo que el amor te quita, te lo devuelve con intereses y te hace querer, y queriendo todo de la otra persona. El amor al igual que cuando no muere puede matar, cuando revive te sana desde un ara\u00f1azo hasta el dolor del coraz\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T11:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/web_portadaloquierotododeti_1085mm-compressed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"601\" \/>\n\t<meta property=\"og:image:height\" content=\"881\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/\",\"name\":\"Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/web_portadaloquierotododeti_1085mm-compressed.jpg\",\"datePublished\":\"2024-04-29T14:14:01+00:00\",\"dateModified\":\"2024-07-30T11:27:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/web_portadaloquierotododeti_1085mm-compressed.jpg\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/web_portadaloquierotododeti_1085mm-compressed.jpg\",\"width\":601,\"height\":881},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/lo-quiero-todo-de-ti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lo quiero todo de ti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"width\":394,\"height\":128,\"caption\":\"Catalogo | Letrame Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/","og_locale":"es_ES","og_type":"article","og_title":"Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial","og_description":"ISBN: 978-84-1144-943-4  SINOPSIS  LO QUIERO TODO DE TI es la bonita historia de amor de JESUS y ANABEL unos amigos, que desde peque\u00f1os hicieron novillos en la plaza de su barrio, entre juego y juego, cada vez se acercaban mas sus corazones, casi sin querer, como por inercia, pero el respeto mutuo entre los dos, encorsetaba de alguna forma el idilio reciproco que por su mismo impulso hubiera florecido. JESUS, en su temor de perderla, le dio un brote de valent\u00eda de los que solo le dan a los que est\u00e1n luchando por su amor, bes\u00f3 a ANABEL en los labios creyendo que as\u00ed ya seria para \u00e9l, pero \u00e9sta se asusto o mas bien sus propios pensamientos le jug\u00f3 una mala pasada y a partir de ah\u00ed, su vida no tiene nada que ver con la vida que so\u00f1aba, ni con quien la so\u00f1aba, y aunque tuvo la posibilidad de tener lo que quisiera en la vida, su esencia de mujer se lo repel\u00eda, se dio cuenta tarde de que escogi\u00f3 una vida que no comulgaba con ella, y por consecuencia, la vida le zarandeo, aunque ella supo salir ilesa en conciencia. Y ademas pudo comprobar con todos sus sentidos, que lo que el amor te quita, te lo devuelve con intereses y te hace querer, y queriendo todo de la otra persona. El amor al igual que cuando no muere puede matar, cuando revive te sana desde un ara\u00f1azo hasta el dolor del coraz\u00f3n.","og_url":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/","og_site_name":"Catalogo | Letrame Grupo Editorial","article_modified_time":"2024-07-30T11:27:09+00:00","og_image":[{"width":601,"height":881,"url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/web_portadaloquierotododeti_1085mm-compressed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/","url":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/","name":"Lo quiero todo de ti - Catalogo | Letrame Grupo Editorial","isPartOf":{"@id":"https:\/\/letrame.com\/catalogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/#primaryimage"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/#primaryimage"},"thumbnailUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/web_portadaloquierotododeti_1085mm-compressed.jpg","datePublished":"2024-04-29T14:14:01+00:00","dateModified":"2024-07-30T11:27:09+00:00","breadcrumb":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/#primaryimage","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/web_portadaloquierotododeti_1085mm-compressed.jpg","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/web_portadaloquierotododeti_1085mm-compressed.jpg","width":601,"height":881},{"@type":"BreadcrumbList","@id":"https:\/\/letrame.com\/catalogo\/producto\/lo-quiero-todo-de-ti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":3,"name":"Lo quiero todo de ti"}]},{"@type":"WebSite","@id":"https:\/\/letrame.com\/catalogo\/#website","url":"https:\/\/letrame.com\/catalogo\/","name":"Catalogo | Letrame Grupo Editorial","description":"","publisher":{"@id":"https:\/\/letrame.com\/catalogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrame.com\/catalogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrame.com\/catalogo\/#organization","name":"Catalogo | Letrame Grupo Editorial","url":"https:\/\/letrame.com\/catalogo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","width":394,"height":128,"caption":"Catalogo | Letrame Grupo Editorial"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product\/99351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/comments?post=99351"}],"acf:post":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/author_book\/77702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media\/99352"}],"wp:attachment":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media?parent=99351"}],"wp:term":[{"taxonomy":"libro","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/libro?post=99351"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_brand?post=99351"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_cat?post=99351"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_tag?post=99351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}