{"id":93655,"date":"2024-04-18T09:34:25","date_gmt":"2024-04-18T07:34:25","guid":{"rendered":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/"},"modified":"2024-05-15T11:23:07","modified_gmt":"2024-05-15T09:23:07","slug":"historia-cronologica-del-flamenco-y-sus-estilos","status":"publish","type":"product","link":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/","title":{"rendered":"Historia cron\u00f3logica del flamenco y sus estilos"},"content":{"rendered":"<p><strong>ISBN<\/strong>: 978-8417161675<br \/>\n<strong>T\u00edtulo<\/strong>: Historia cron\u00f3logica del flamenco y sus estilos<br \/>\n<strong>Fecha<\/strong>: 2017<br \/>\n<strong>P\u00e1ginas<\/strong>: 196<\/p>\n<p>&nbsp;<\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>A pesar de que el flamenco es declarado por la UNESCO como \u201cPatrimonio Cultural Inmaterial de la Humanidad\u201d y es conocido en todos los continentes, sigue siendo el gran desconocido como arte impl\u00edcito, debido a la complejidad de su m\u00fasica y la gran cantidad de los estilos o \u201cpalos\u201d que lo forman&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>ISBN: 978-8417161675<\/strong><\/p>\n<p>A pesar de que el flamenco es declarado por la UNESCO como \u201cPatrimonio Cultural Inmaterial de la Humanidad\u201d y es conocido en todos los continentes, sigue siendo el gran desconocido como arte impl\u00edcito, debido a la complejidad de su m\u00fasica y la gran cantidad de los estilos o \u201cpalos\u201d que lo forman&#8230;<\/p>\n","protected":false},"featured_media":99948,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"libro":[],"product_brand":[],"product_cat":[22],"product_tag":[],"class_list":{"0":"post-93655","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-docencia","8":"first","9":"instock","10":"purchasable","11":"product-type-simple"},"acf":{"autor":"","enlace_de_compra":"https:\/\/www.amazon.es\/Historia-cronol%C3%B3gica-flamenco-estilos-Docencia\/dp\/8417161678\/ref=sr_1_1?__mk_es_ES=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp&dchild=1&amp&keywords=Historia+cron%C3%B3logica+del+flamenco+y+sus+estilos+letrame&amp&qid=1591884120&amp&s=books&amp&sr=1-1"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"ISBN: 978-8417161675  A pesar de que el flamenco es declarado por la UNESCO como \u201cPatrimonio Cultural Inmaterial de la Humanidad\u201d y es conocido en todos los continentes, sigue siendo el gran desconocido como arte impl\u00edcito, debido a la complejidad de su m\u00fasica y la gran cantidad de los estilos o \u201cpalos\u201d que lo forman...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-15T09:23:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/Historia-cronologica-del-flamenco-y-sus-estilos.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"375\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/\",\"name\":\"Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Historia-cronologica-del-flamenco-y-sus-estilos.webp\",\"datePublished\":\"2024-04-18T07:34:25+00:00\",\"dateModified\":\"2024-05-15T09:23:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Historia-cronologica-del-flamenco-y-sus-estilos.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Historia-cronologica-del-flamenco-y-sus-estilos.webp\",\"width\":375,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/historia-cronologica-del-flamenco-y-sus-estilos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Historia cron\u00f3logica del flamenco y sus estilos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"width\":394,\"height\":128,\"caption\":\"Catalogo | Letrame Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/","og_locale":"es_ES","og_type":"article","og_title":"Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial","og_description":"ISBN: 978-8417161675  A pesar de que el flamenco es declarado por la UNESCO como \u201cPatrimonio Cultural Inmaterial de la Humanidad\u201d y es conocido en todos los continentes, sigue siendo el gran desconocido como arte impl\u00edcito, debido a la complejidad de su m\u00fasica y la gran cantidad de los estilos o \u201cpalos\u201d que lo forman...","og_url":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/","og_site_name":"Catalogo | Letrame Grupo Editorial","article_modified_time":"2024-05-15T09:23:07+00:00","og_image":[{"width":375,"height":525,"url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/Historia-cronologica-del-flamenco-y-sus-estilos.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/","url":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/","name":"Historia cron\u00f3logica del flamenco y sus estilos - Catalogo | Letrame Grupo Editorial","isPartOf":{"@id":"https:\/\/letrame.com\/catalogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/#primaryimage"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/#primaryimage"},"thumbnailUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/Historia-cronologica-del-flamenco-y-sus-estilos.webp","datePublished":"2024-04-18T07:34:25+00:00","dateModified":"2024-05-15T09:23:07+00:00","breadcrumb":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/#primaryimage","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/Historia-cronologica-del-flamenco-y-sus-estilos.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/04\/Historia-cronologica-del-flamenco-y-sus-estilos.webp","width":375,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/letrame.com\/catalogo\/producto\/historia-cronologica-del-flamenco-y-sus-estilos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":3,"name":"Historia cron\u00f3logica del flamenco y sus estilos"}]},{"@type":"WebSite","@id":"https:\/\/letrame.com\/catalogo\/#website","url":"https:\/\/letrame.com\/catalogo\/","name":"Catalogo | Letrame Grupo Editorial","description":"","publisher":{"@id":"https:\/\/letrame.com\/catalogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrame.com\/catalogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrame.com\/catalogo\/#organization","name":"Catalogo | Letrame Grupo Editorial","url":"https:\/\/letrame.com\/catalogo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","width":394,"height":128,"caption":"Catalogo | Letrame Grupo Editorial"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product\/93655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/comments?post=93655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media\/99948"}],"wp:attachment":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media?parent=93655"}],"wp:term":[{"taxonomy":"libro","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/libro?post=93655"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_brand?post=93655"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_cat?post=93655"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_tag?post=93655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}