{"id":113345,"date":"2026-06-24T15:19:21","date_gmt":"2026-06-24T13:19:21","guid":{"rendered":"https:\/\/letrame.com\/catalogo\/?post_type=product&#038;p=113345"},"modified":"2026-07-03T13:25:54","modified_gmt":"2026-07-03T11:25:54","slug":"vauman","status":"publish","type":"product","link":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/","title":{"rendered":"Vauman"},"content":{"rendered":"<p><strong>ISBN: 9791370542641<\/strong><br \/>\n<strong>T\u00edtulo: Vauman<\/strong><br \/>\n<strong>Fecha: 2026<\/strong><br \/>\n<strong>P\u00e1ginas: 178<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>Transilvania, 1309. En una tierra asolada por la guerra entre hombres lobo y vampiros, los humanos luchan por sobrevivir al invierno y a las criaturas que acechan en los bosques.<\/p>\n<p>Juan, l\u00edder de su aldea, y su hermano Mircea se embarcan en una cacer\u00eda desesperada que los llevar\u00e1 a enfrentarse a horrores inimaginables.<\/p>\n<p>Pero el verdadero conflicto nace con Vauman, un h\u00edbrido criado por vampiros que debe enfrentarse a Cornel, su hermano y l\u00edder de los hombres lobo. Entre traiciones, alianzas imposibles y secretos que pueden destruir todo, Vauman deber\u00e1 decidir qu\u00e9 pesa m\u00e1s: su familia o el futuro de toda Transilvania.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>ISBN: 9791370542641<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>Transilvania, 1309. En una tierra asolada por la guerra entre hombres lobo y vampiros, los humanos luchan por sobrevivir al invierno y a las criaturas que acechan en los bosques.<\/p>\n<p>Juan, l\u00edder de su aldea, y su hermano Mircea se embarcan en una cacer\u00eda desesperada que los llevar\u00e1 a enfrentarse a horrores inimaginables.<\/p>\n<p>Pero el verdadero conflicto nace con Vauman, un h\u00edbrido criado por vampiros que debe enfrentarse a Cornel, su hermano y l\u00edder de los hombres lobo. Entre traiciones, alianzas imposibles y secretos que pueden destruir todo, Vauman deber\u00e1 decidir qu\u00e9 pesa m\u00e1s: su familia o el futuro de toda Transilvania.<\/p>\n","protected":false},"featured_media":113349,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"libro":[],"product_brand":[],"product_cat":[118],"product_tag":[],"class_list":["post-113345","product","type-product","status-publish","has-post-thumbnail","product_cat-fantasia","first","instock","shipping-taxable","product-type-simple"],"acf":{"autor":[111129],"enlace_de_compra":"https:\/\/amzn.to\/4wlo0jD"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vauman - Catalogo | Letrame Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrame.com\/catalogo\/producto\/vauman\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vauman - Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"ISBN: 9791370542641  SINOPSIS  Transilvania, 1309. En una tierra asolada por la guerra entre hombres lobo y vampiros, los humanos luchan por sobrevivir al invierno y a las criaturas que acechan en los bosques.  Juan, l\u00edder de su aldea, y su hermano Mircea se embarcan en una cacer\u00eda desesperada que los llevar\u00e1 a enfrentarse a horrores inimaginables.  Pero el verdadero conflicto nace con Vauman, un h\u00edbrido criado por vampiros que debe enfrentarse a Cornel, su hermano y l\u00edder de los hombres lobo. Entre traiciones, alianzas imposibles y secretos que pueden destruir todo, Vauman deber\u00e1 decidir qu\u00e9 pesa m\u00e1s: su familia o el futuro de toda Transilvania.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrame.com\/catalogo\/producto\/vauman\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T11:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/vauman_893mm4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"827\" \/>\n\t<meta property=\"og:image:height\" content=\"1158\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/\",\"name\":\"Vauman - Catalogo | Letrame Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/vauman_893mm4.jpg\",\"datePublished\":\"2026-06-24T13:19:21+00:00\",\"dateModified\":\"2026-07-03T11:25:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/vauman_893mm4.jpg\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/vauman_893mm4.jpg\",\"width\":827,\"height\":1158},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/vauman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vauman\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"width\":394,\"height\":128,\"caption\":\"Catalogo | Letrame Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vauman - Catalogo | Letrame Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/","og_locale":"es_ES","og_type":"article","og_title":"Vauman - Catalogo | Letrame Grupo Editorial","og_description":"ISBN: 9791370542641  SINOPSIS  Transilvania, 1309. En una tierra asolada por la guerra entre hombres lobo y vampiros, los humanos luchan por sobrevivir al invierno y a las criaturas que acechan en los bosques.  Juan, l\u00edder de su aldea, y su hermano Mircea se embarcan en una cacer\u00eda desesperada que los llevar\u00e1 a enfrentarse a horrores inimaginables.  Pero el verdadero conflicto nace con Vauman, un h\u00edbrido criado por vampiros que debe enfrentarse a Cornel, su hermano y l\u00edder de los hombres lobo. Entre traiciones, alianzas imposibles y secretos que pueden destruir todo, Vauman deber\u00e1 decidir qu\u00e9 pesa m\u00e1s: su familia o el futuro de toda Transilvania.","og_url":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/","og_site_name":"Catalogo | Letrame Grupo Editorial","article_modified_time":"2026-07-03T11:25:54+00:00","og_image":[{"width":827,"height":1158,"url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/vauman_893mm4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/","url":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/","name":"Vauman - Catalogo | Letrame Grupo Editorial","isPartOf":{"@id":"https:\/\/letrame.com\/catalogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/#primaryimage"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/#primaryimage"},"thumbnailUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/vauman_893mm4.jpg","datePublished":"2026-06-24T13:19:21+00:00","dateModified":"2026-07-03T11:25:54+00:00","breadcrumb":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrame.com\/catalogo\/producto\/vauman\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/#primaryimage","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/vauman_893mm4.jpg","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/vauman_893mm4.jpg","width":827,"height":1158},{"@type":"BreadcrumbList","@id":"https:\/\/letrame.com\/catalogo\/producto\/vauman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":3,"name":"Vauman"}]},{"@type":"WebSite","@id":"https:\/\/letrame.com\/catalogo\/#website","url":"https:\/\/letrame.com\/catalogo\/","name":"Catalogo | Letrame Grupo Editorial","description":"","publisher":{"@id":"https:\/\/letrame.com\/catalogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrame.com\/catalogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrame.com\/catalogo\/#organization","name":"Catalogo | Letrame Grupo Editorial","url":"https:\/\/letrame.com\/catalogo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","width":394,"height":128,"caption":"Catalogo | Letrame Grupo Editorial"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product\/113345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/comments?post=113345"}],"acf:post":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/author_book\/111129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media\/113349"}],"wp:attachment":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media?parent=113345"}],"wp:term":[{"taxonomy":"libro","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/libro?post=113345"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_brand?post=113345"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_cat?post=113345"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_tag?post=113345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}