{"id":113335,"date":"2026-06-24T13:57:29","date_gmt":"2026-06-24T11:57:29","guid":{"rendered":"https:\/\/letrame.com\/catalogo\/?post_type=product&#038;p=113335"},"modified":"2026-07-03T13:24:30","modified_gmt":"2026-07-03T11:24:30","slug":"capitan-tartamudo","status":"publish","type":"product","link":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/","title":{"rendered":"Capit\u00e1n Tartamudo"},"content":{"rendered":"<p><strong>ISBN: 9791370299057<\/strong><br \/>\n<strong>T\u00edtulo: Capit\u00e1n Tartamudo<\/strong><br \/>\n<strong>Fecha: 2026<\/strong><br \/>\n<strong>P\u00e1ginas: 216<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>El Capit\u00e1n Tartamudo no es un pirata cualquiera. Tiene un barco lleno de cicatrices, una voz que tropieza con las palabras y un coraz\u00f3n m\u00e1s grande que cualquier oc\u00e9ano.<\/p>\n<p>Desde ni\u00f1o escuch\u00f3 historias sobre un tesoro imposible, islas m\u00e1gicas y un drag\u00f3n legendario llamado Escarlata\u2026<\/p>\n<p>Junto a su fiel perro P\u00e1jaro y una tripulaci\u00f3n tan valiente como disparatada, se lanza al mar en busca de pruebas que pondr\u00e1n a prueba algo m\u00e1s importante que la fuerza o el oro: la lealtad, la amistad y el valor de hacer lo correcto.<\/p>\n<p>Dragones, guardianes, enigmas, criaturas imposibles y decisiones que cambian destinos esperan en este viaje donde el verdadero tesoro no siempre brilla\u2026 pero deja huella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>ISBN: 9791370299057<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p>El Capit\u00e1n Tartamudo no es un pirata cualquiera. Tiene un barco lleno de cicatrices, una voz que tropieza con las palabras y un coraz\u00f3n m\u00e1s grande que cualquier oc\u00e9ano.<\/p>\n<p>Desde ni\u00f1o escuch\u00f3 historias sobre un tesoro imposible, islas m\u00e1gicas y un drag\u00f3n legendario llamado Escarlata\u2026<\/p>\n<p>Junto a su fiel perro P\u00e1jaro y una tripulaci\u00f3n tan valiente como disparatada, se lanza al mar en busca de pruebas que pondr\u00e1n a prueba algo m\u00e1s importante que la fuerza o el oro: la lealtad, la amistad y el valor de hacer lo correcto.<\/p>\n<p>Dragones, guardianes, enigmas, criaturas imposibles y decisiones que cambian destinos esperan en este viaje donde el verdadero tesoro no siempre brilla\u2026 pero deja huella.<\/p>\n","protected":false},"featured_media":113338,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"libro":[],"product_brand":[],"product_cat":[17,134],"product_tag":[],"class_list":["post-113335","product","type-product","status-publish","has-post-thumbnail","product_cat-infantil","product_cat-juvenil","first","instock","shipping-taxable","product-type-simple"],"acf":{"autor":"","enlace_de_compra":"https:\/\/amzn.to\/3QzqP1x"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"ISBN: 9791370299057  SINOPSIS  El Capit\u00e1n Tartamudo no es un pirata cualquiera. Tiene un barco lleno de cicatrices, una voz que tropieza con las palabras y un coraz\u00f3n m\u00e1s grande que cualquier oc\u00e9ano.  Desde ni\u00f1o escuch\u00f3 historias sobre un tesoro imposible, islas m\u00e1gicas y un drag\u00f3n legendario llamado Escarlata\u2026  Junto a su fiel perro P\u00e1jaro y una tripulaci\u00f3n tan valiente como disparatada, se lanza al mar en busca de pruebas que pondr\u00e1n a prueba algo m\u00e1s importante que la fuerza o el oro: la lealtad, la amistad y el valor de hacer lo correcto.  Dragones, guardianes, enigmas, criaturas imposibles y decisiones que cambian destinos esperan en este viaje donde el verdadero tesoro no siempre brilla\u2026 pero deja huella.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T11:24:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-135647.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"1367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/\",\"name\":\"Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-pantalla-2026-06-24-135647.jpg\",\"datePublished\":\"2026-06-24T11:57:29+00:00\",\"dateModified\":\"2026-07-03T11:24:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-pantalla-2026-06-24-135647.jpg\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Captura-de-pantalla-2026-06-24-135647.jpg\",\"width\":910,\"height\":1367},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/capitan-tartamudo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capit\u00e1n Tartamudo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"width\":394,\"height\":128,\"caption\":\"Catalogo | Letrame Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/","og_locale":"es_ES","og_type":"article","og_title":"Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial","og_description":"ISBN: 9791370299057  SINOPSIS  El Capit\u00e1n Tartamudo no es un pirata cualquiera. Tiene un barco lleno de cicatrices, una voz que tropieza con las palabras y un coraz\u00f3n m\u00e1s grande que cualquier oc\u00e9ano.  Desde ni\u00f1o escuch\u00f3 historias sobre un tesoro imposible, islas m\u00e1gicas y un drag\u00f3n legendario llamado Escarlata\u2026  Junto a su fiel perro P\u00e1jaro y una tripulaci\u00f3n tan valiente como disparatada, se lanza al mar en busca de pruebas que pondr\u00e1n a prueba algo m\u00e1s importante que la fuerza o el oro: la lealtad, la amistad y el valor de hacer lo correcto.  Dragones, guardianes, enigmas, criaturas imposibles y decisiones que cambian destinos esperan en este viaje donde el verdadero tesoro no siempre brilla\u2026 pero deja huella.","og_url":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/","og_site_name":"Catalogo | Letrame Grupo Editorial","article_modified_time":"2026-07-03T11:24:30+00:00","og_image":[{"width":910,"height":1367,"url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-135647.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/","url":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/","name":"Capit\u00e1n Tartamudo - Catalogo | Letrame Grupo Editorial","isPartOf":{"@id":"https:\/\/letrame.com\/catalogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/#primaryimage"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/#primaryimage"},"thumbnailUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-135647.jpg","datePublished":"2026-06-24T11:57:29+00:00","dateModified":"2026-07-03T11:24:30+00:00","breadcrumb":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/#primaryimage","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-135647.jpg","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/06\/Captura-de-pantalla-2026-06-24-135647.jpg","width":910,"height":1367},{"@type":"BreadcrumbList","@id":"https:\/\/letrame.com\/catalogo\/producto\/capitan-tartamudo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":3,"name":"Capit\u00e1n Tartamudo"}]},{"@type":"WebSite","@id":"https:\/\/letrame.com\/catalogo\/#website","url":"https:\/\/letrame.com\/catalogo\/","name":"Catalogo | Letrame Grupo Editorial","description":"","publisher":{"@id":"https:\/\/letrame.com\/catalogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrame.com\/catalogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrame.com\/catalogo\/#organization","name":"Catalogo | Letrame Grupo Editorial","url":"https:\/\/letrame.com\/catalogo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","width":394,"height":128,"caption":"Catalogo | Letrame Grupo Editorial"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product\/113335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/comments?post=113335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media\/113338"}],"wp:attachment":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media?parent=113335"}],"wp:term":[{"taxonomy":"libro","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/libro?post=113335"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_brand?post=113335"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_cat?post=113335"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_tag?post=113335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}