{"id":112100,"date":"2026-04-13T20:18:03","date_gmt":"2026-04-13T18:18:03","guid":{"rendered":"https:\/\/letrame.com\/catalogo\/?post_type=product&#038;p=112100"},"modified":"2026-04-13T20:18:04","modified_gmt":"2026-04-13T18:18:04","slug":"el-diario-de-una-oveja-negra","status":"publish","type":"product","link":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/","title":{"rendered":"El diario de una oveja negra"},"content":{"rendered":"<p><strong>ISBN: 9791370298081<\/strong><br \/>\n<strong>T\u00edtulo: El diario de una oveja negra<\/strong><br \/>\n<strong>Fecha: 2026<\/strong><br \/>\n<strong>P\u00e1ginas: 76<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p data-start=\"0\" data-end=\"103\">A veces la vida aprieta tanto que lo \u00fanico que queda es escribir, respirar, latir, rompernos\u2026 y seguir.<\/p>\n<p data-start=\"105\" data-end=\"403\">Mariana Luminita comparte con nosotros un cuaderno abierto al alma, lleno de pensamientos desordenados, emociones a flor de piel y palabras que salen sin pedir permiso. Nos habla del amor que duele, del apego, del cansancio, de las ganas de huir, de los momentos de lucidez y de otros de puro caos.<\/p>\n<p data-start=\"405\" data-end=\"641\">Atraviesa relaciones que apagan, inseguridades, el vino como refugio, el deseo de sentirse peque\u00f1a, de perderse\u2026 y, poco a poco, de empezar a encontrarse. Cada texto es una especie de conversaci\u00f3n consigo misma en la que nos deja estar.<\/p>\n<p data-start=\"643\" data-end=\"850\"><em data-start=\"643\" data-end=\"673\">El diario de una oveja negra<\/em> es la voz valiente de alguien que aprende a ponerse primero, aunque todav\u00eda le tiemblen las manos. Es un diario emocional: a ratos triste, a ratos rebelde, a ratos muy honesto.<\/p>\n<p data-start=\"852\" data-end=\"894\" data-is-last-node=\"\" data-is-only-node=\"\">Una oveja negra que deja de pedir permiso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>ISBN: 9791370298081<\/strong><\/p>\n<p><strong>SINOPSIS<\/strong><\/p>\n<p data-start=\"0\" data-end=\"103\">A veces la vida aprieta tanto que lo \u00fanico que queda es escribir, respirar, latir, rompernos\u2026 y seguir.<\/p>\n<p data-start=\"105\" data-end=\"403\">Mariana Luminita comparte con nosotros un cuaderno abierto al alma, lleno de pensamientos desordenados, emociones a flor de piel y palabras que salen sin pedir permiso. Nos habla del amor que duele, del apego, del cansancio, de las ganas de huir, de los momentos de lucidez y de otros de puro caos.<\/p>\n<p data-start=\"405\" data-end=\"641\">Atraviesa relaciones que apagan, inseguridades, el vino como refugio, el deseo de sentirse peque\u00f1a, de perderse\u2026 y, poco a poco, de empezar a encontrarse. Cada texto es una especie de conversaci\u00f3n consigo misma en la que nos deja estar.<\/p>\n<p data-start=\"643\" data-end=\"850\"><em data-start=\"643\" data-end=\"673\">El diario de una oveja negra<\/em> es la voz valiente de alguien que aprende a ponerse primero, aunque todav\u00eda le tiemblen las manos. Es un diario emocional: a ratos triste, a ratos rebelde, a ratos muy honesto.<\/p>\n<p data-start=\"852\" data-end=\"894\" data-is-last-node=\"\" data-is-only-node=\"\">Una oveja negra que deja de pedir permiso.<\/p>\n","protected":false},"featured_media":112103,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"libro":[],"product_brand":[],"product_cat":[20],"product_tag":[],"class_list":["post-112100","product","type-product","status-publish","has-post-thumbnail","product_cat-poesia","first","instock","shipping-taxable","product-type-simple"],"acf":{"autor":[112101],"enlace_de_compra":"https:\/\/amzn.to\/3OFeFmB"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El diario de una oveja negra - Catalogo | Letrame Grupo Editorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El diario de una oveja negra - Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"og:description\" content=\"ISBN: 9791370298081  SINOPSIS A veces la vida aprieta tanto que lo \u00fanico que queda es escribir, respirar, latir, rompernos\u2026 y seguir. Mariana Luminita comparte con nosotros un cuaderno abierto al alma, lleno de pensamientos desordenados, emociones a flor de piel y palabras que salen sin pedir permiso. Nos habla del amor que duele, del apego, del cansancio, de las ganas de huir, de los momentos de lucidez y de otros de puro caos. Atraviesa relaciones que apagan, inseguridades, el vino como refugio, el deseo de sentirse peque\u00f1a, de perderse\u2026 y, poco a poco, de empezar a encontrarse. Cada texto es una especie de conversaci\u00f3n consigo misma en la que nos deja estar. El diario de una oveja negra es la voz valiente de alguien que aprende a ponerse primero, aunque todav\u00eda le tiemblen las manos. Es un diario emocional: a ratos triste, a ratos rebelde, a ratos muy honesto. Una oveja negra que deja de pedir permiso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/\" \/>\n<meta property=\"og:site_name\" content=\"Catalogo | Letrame Grupo Editorial\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T18:18:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/04\/eldiariode_44mm4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"699\" \/>\n\t<meta property=\"og:image:height\" content=\"992\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/\",\"name\":\"El diario de una oveja negra - Catalogo | Letrame Grupo Editorial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/eldiariode_44mm4.jpg\",\"datePublished\":\"2026-04-13T18:18:03+00:00\",\"dateModified\":\"2026-04-13T18:18:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/eldiariode_44mm4.jpg\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/eldiariode_44mm4.jpg\",\"width\":699,\"height\":992},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/producto\\\/el-diario-de-una-oveja-negra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El diario de una oveja negra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#website\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#organization\",\"name\":\"Catalogo | Letrame Grupo Editorial\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"contentUrl\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo2.webp\",\"width\":394,\"height\":128,\"caption\":\"Catalogo | Letrame Grupo Editorial\"},\"image\":{\"@id\":\"https:\\\/\\\/letrame.com\\\/catalogo\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El diario de una oveja negra - Catalogo | Letrame Grupo Editorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/","og_locale":"es_ES","og_type":"article","og_title":"El diario de una oveja negra - Catalogo | Letrame Grupo Editorial","og_description":"ISBN: 9791370298081  SINOPSIS A veces la vida aprieta tanto que lo \u00fanico que queda es escribir, respirar, latir, rompernos\u2026 y seguir. Mariana Luminita comparte con nosotros un cuaderno abierto al alma, lleno de pensamientos desordenados, emociones a flor de piel y palabras que salen sin pedir permiso. Nos habla del amor que duele, del apego, del cansancio, de las ganas de huir, de los momentos de lucidez y de otros de puro caos. Atraviesa relaciones que apagan, inseguridades, el vino como refugio, el deseo de sentirse peque\u00f1a, de perderse\u2026 y, poco a poco, de empezar a encontrarse. Cada texto es una especie de conversaci\u00f3n consigo misma en la que nos deja estar. El diario de una oveja negra es la voz valiente de alguien que aprende a ponerse primero, aunque todav\u00eda le tiemblen las manos. Es un diario emocional: a ratos triste, a ratos rebelde, a ratos muy honesto. Una oveja negra que deja de pedir permiso.","og_url":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/","og_site_name":"Catalogo | Letrame Grupo Editorial","article_modified_time":"2026-04-13T18:18:04+00:00","og_image":[{"width":699,"height":992,"url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/04\/eldiariode_44mm4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/","url":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/","name":"El diario de una oveja negra - Catalogo | Letrame Grupo Editorial","isPartOf":{"@id":"https:\/\/letrame.com\/catalogo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/#primaryimage"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/#primaryimage"},"thumbnailUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/04\/eldiariode_44mm4.jpg","datePublished":"2026-04-13T18:18:03+00:00","dateModified":"2026-04-13T18:18:04+00:00","breadcrumb":{"@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/#primaryimage","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/04\/eldiariode_44mm4.jpg","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2026\/04\/eldiariode_44mm4.jpg","width":699,"height":992},{"@type":"BreadcrumbList","@id":"https:\/\/letrame.com\/catalogo\/producto\/el-diario-de-una-oveja-negra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/letrame.com\/catalogo\/"},{"@type":"ListItem","position":3,"name":"El diario de una oveja negra"}]},{"@type":"WebSite","@id":"https:\/\/letrame.com\/catalogo\/#website","url":"https:\/\/letrame.com\/catalogo\/","name":"Catalogo | Letrame Grupo Editorial","description":"","publisher":{"@id":"https:\/\/letrame.com\/catalogo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letrame.com\/catalogo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/letrame.com\/catalogo\/#organization","name":"Catalogo | Letrame Grupo Editorial","url":"https:\/\/letrame.com\/catalogo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/","url":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","contentUrl":"https:\/\/letrame.com\/catalogo\/wp-content\/uploads\/2024\/03\/logo2.webp","width":394,"height":128,"caption":"Catalogo | Letrame Grupo Editorial"},"image":{"@id":"https:\/\/letrame.com\/catalogo\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product\/112100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/comments?post=112100"}],"acf:post":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/author_book\/112101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media\/112103"}],"wp:attachment":[{"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/media?parent=112100"}],"wp:term":[{"taxonomy":"libro","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/libro?post=112100"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_brand?post=112100"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_cat?post=112100"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/letrame.com\/catalogo\/wp-json\/wp\/v2\/product_tag?post=112100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}